{"id":14839,"date":"2024-09-16T17:51:36","date_gmt":"2024-09-16T15:51:36","guid":{"rendered":"https:\/\/artgerecht.shop\/p\/unkategorisiert\/the-goodstuff-adult-dogs-huhn-2-5kg\/"},"modified":"2026-09-02T11:21:56","modified_gmt":"2026-09-02T10:21:56","slug":"the-goodstuff-huhn-2-5-kg","status":"publish","type":"product","link":"https:\/\/artgerecht.shop\/de\/p\/the-goodstuff-huhn-2-5-kg\/","title":{"rendered":"<span class=\"brand\">THE GOODSTUFF<\/span> Huhn \u2013 2.5 kg"},"content":{"rendered":"<p>Trockenfutter Huhn f\u00fcr ausgewachsene Hunde in bew\u00e4hrter THE GOODSTUFF Super Premium-Qualit\u00e4t. Ein ideales Alleinfuttermittel f\u00fcr Hunde aller Rassen und Gr\u00f6\u00dfen mit normaler Aktivit\u00e4t. Schonend hergestellt ohne Getreide, reich an frischem H\u00fchner- &amp; Puten-Muskelfleisch in Lebensmittelqualit\u00e4t, Amaranth mit niedrigem glyk\u00e4mischen Index, regional verf\u00fcgbarem Obst &amp; Gem\u00fcse sowie ausgew\u00e4hlten Kr\u00e4utern.<\/p>\n<p>Alle unsere Rezepturen sind Single Protein, hergestellt mit frischem Fleisch in Lebensmittelqualit\u00e4t, regional verf\u00fcgbaren Rohstoffen und immer ohne Verwendung von Getreide. Wir setzen auf eine einheitliche, klar verst\u00e4ndliche und reduzierte Rezeptur, welche jederzeit erlaubt, bedenkenlos innerhalb einer Produktfamilie zwischen den verschiedenen Fleischsorten wechseln zu k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Hergestellt mit frischem Fleisch<\/li>\n<li>Hergestellt ohne Getreide<\/li>\n<li>Entwickelt in \u00d6sterreich, hergestellt in Deutschland<\/li>\n<\/ul>\n","protected":false},"featured_media":17617,"template":"","meta":{"_acf_changed":false},"product_brand":[106],"product_cat":[232],"product_tag":[],"product_attribute_cat":[70],"class_list":["post-14839","product","type-product","status-publish","has-post-thumbnail","product_brand-the-goodstuff","product_cat-hunde_futter_trockenfutter","pa_geschmack-gefluegel","pa_geschmack-huhn","pa_inhalt-2-5-kg","pa_lebensphase-adult","pa_verpackung-sack","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/product\/14839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/media\/17617"}],"wp:attachment":[{"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/media?parent=14839"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/product_brand?post=14839"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/product_cat?post=14839"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/product_tag?post=14839"},{"taxonomy":"product_attribute_cat","embeddable":true,"href":"https:\/\/artgerecht.shop\/de\/wp-json\/wp\/v2\/product_attribute_cat?post=14839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}